{"id":30056,"date":"2026-09-01T09:45:02","date_gmt":"2026-09-01T09:45:02","guid":{"rendered":"https:\/\/www.g-portal.com\/wiki\/?p=30056"},"modified":"2026-09-01T09:45:27","modified_gmt":"2026-09-01T09:45:27","slug":"wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein","status":"publish","type":"post","link":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/","title":{"rendered":"Wie miete ich meinen Server f\u00fcr Scum bei GPORTAL und richte ihn ein? (Video)"},"content":{"rendered":"\n<p>Unser Partner <a href=\"https:\/\/www.youtube.com\/@JasonDugs\">Jason Dugs<\/a> hat f\u00fcr dich eine einfache Schritt-f\u00fcr-Schritt-Anleitung auf <a href=\"https:\/\/www.youtube.com\/watch?v=Uy24sOkGYVM\">YouTube<\/a> hochgeladen, wie du deinen Scum Server ruckzuck aufsetzen kannst und gibt dann sogar noch fortgeschrittene Tipps f\u00fcr die Konfiguration deines Servers.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Private Server f\u00fcr SCUM 1.0 Release [Info GER] by GPORTAL mit 10% Rabatt\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/fycJyKYJjuI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Unser Partner Jason Dugs hat f\u00fcr dich eine einfache Schritt-f\u00fcr-Schritt-Anleitung auf YouTube hochgeladen, wie du deinen Scum Server ruckzuck aufsetzen kannst und gibt dann sogar noch fortgeschrittene Tipps f\u00fcr die Konfiguration deines Servers.<\/p>\n","protected":false},"author":16,"featured_media":15630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-blog-template.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,23],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki<\/title>\n<meta name=\"description\" content=\"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki\" \/>\n<meta property=\"og:description\" content=\"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/\" \/>\n<meta property=\"og:site_name\" content=\"GPORTAL Wiki\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T09:45:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:45:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"35\" \/>\n\t<meta property=\"og:image:height\" content=\"20\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Steven\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steven\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/\",\"name\":\"Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki\",\"isPartOf\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp\",\"datePublished\":\"2026-09-01T09:45:02+00:00\",\"dateModified\":\"2026-09-01T09:45:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/6c8d17638d38be4b951b9d1564636faf\"},\"description\":\"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken\",\"breadcrumb\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp\",\"contentUrl\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp\",\"width\":35,\"height\":20},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.g-portal.com\/wiki\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie miete ich meinen Server f\u00fcr Scum bei GPORTAL und richte ihn ein? (Video)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#website\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/en\/\",\"name\":\"GPORTAL Wiki\",\"description\":\"GPORTAL Wiki\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.g-portal.com\/wiki\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/6c8d17638d38be4b951b9d1564636faf\",\"name\":\"Steven\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ae1e807f2ff968311b283ab8a45e36fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ae1e807f2ff968311b283ab8a45e36fe?s=96&d=mm&r=g\",\"caption\":\"Steven\"},\"url\":\"https:\/\/www.g-portal.com\/wiki\/de\/author\/steven\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki","description":"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/","og_locale":"de_DE","og_type":"article","og_title":"Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki","og_description":"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken","og_url":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/","og_site_name":"GPORTAL Wiki","article_published_time":"2026-09-01T09:45:02+00:00","article_modified_time":"2026-09-01T09:45:27+00:00","og_image":[{"width":35,"height":20,"url":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp","type":"image\/webp"}],"author":"Steven","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Steven","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/","url":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/","name":"Wie richte ich meinen Scum Server bei GPORTAL ein? | GPORTAL Wiki","isPartOf":{"@id":"https:\/\/www.g-portal.com\/wiki\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage"},"image":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp","datePublished":"2026-09-01T09:45:02+00:00","dateModified":"2026-09-01T09:45:27+00:00","author":{"@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/6c8d17638d38be4b951b9d1564636faf"},"description":"So richtest du deinen Scum Server bei GPORTAL ein! \u2666 Schnell und einfach \u2666 Hier klicken","breadcrumb":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#primaryimage","url":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp","contentUrl":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp","width":35,"height":20},{"@type":"BreadcrumbList","@id":"https:\/\/www.g-portal.com\/wiki\/de\/wie-miete-ich-meinen-server-fuer-scum-bei-gportal-und-richte-ihn-ein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.g-portal.com\/wiki\/en\/"},{"@type":"ListItem","position":2,"name":"Wie miete ich meinen Server f\u00fcr Scum bei GPORTAL und richte ihn ein? (Video)"}]},{"@type":"WebSite","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#website","url":"https:\/\/www.g-portal.com\/wiki\/en\/","name":"GPORTAL Wiki","description":"GPORTAL Wiki","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.g-portal.com\/wiki\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/6c8d17638d38be4b951b9d1564636faf","name":"Steven","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ae1e807f2ff968311b283ab8a45e36fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae1e807f2ff968311b283ab8a45e36fe?s=96&d=mm&r=g","caption":"Steven"},"url":"https:\/\/www.g-portal.com\/wiki\/de\/author\/steven\/"}]}},"jetpack_featured_media_url":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/official-servers.webp","_links":{"self":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/30056"}],"collection":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/comments?post=30056"}],"version-history":[{"count":3,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/30056\/revisions"}],"predecessor-version":[{"id":30060,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/30056\/revisions\/30060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/media\/15630"}],"wp:attachment":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/media?parent=30056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/categories?post=30056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/tags?post=30056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}