{"id":697,"date":"2019-07-26T14:01:54","date_gmt":"2019-07-26T14:01:54","guid":{"rendered":"https:\/\/www.g-portal.com\/wiki\/?p=697"},"modified":"2021-09-03T14:44:16","modified_gmt":"2021-09-03T14:44:16","slug":"life-is-feudal","status":"publish","type":"post","link":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/","title":{"rendered":"Life is Feudal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Basis Serverkonfiguration<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Backup erstellen<\/h3>\n\n\n\n<p>Mit Deinem Server bei GPORTAL erh\u00e4ltst Du die M\u00f6glichkeit, Backups anzulegen. Du bekommst von uns kostenlosen Speicherplatz f\u00fcr das Sichern Deiner Spielst\u00e4nde.  <\/p>\n\n\n\n<div class='hint hint--brand'><p><strong>Hinweis<\/strong> Bitte beachte, dass Backups nicht automatisch angelegt werden.  <\/p><\/div>\n\n\n\n<p><strong>So legst du ein Backup \u00fcber das Webinterface an:<\/strong><\/p>\n\n\n\n<ol><li>Logge Dich \u00fcber unsere Webseite ein<\/li><li>Klicke im linken Men\u00fc auf &#8222;<strong>Meine Server<\/strong>&#8222;<\/li><li>W\u00e4hle den gew\u00fcnschten Server aus<\/li><li>Klicke im linken Men\u00fc beim Punkt &#8222;<strong>Administration<\/strong>&#8220; auf &#8222;<strong>Backup<\/strong>&#8222;<\/li><li>Klicke auf &#8222;<strong>Backup erstellen<\/strong>&#8222;<\/li><li>Der Server stoppt f\u00fcr das Backup<\/li><li>Nach der Backup Erstellung startet der <strong>Server automatisch neu<\/strong><\/li><\/ol>\n\n\n\n<div class='hint hint--danger'><p><strong>Wichtig<\/strong> Zwischen 19:00 Uhr und 21:00 Uhr kann kein Backup angelegt werden. <\/p><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\" alt=\"\" data-id=\"1760\" class=\"wp-image-1760\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Logge Dich in Dein <strong>GPORTAL <\/strong>Konto ein<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4.png\" alt=\"\" data-id=\"1763\" data-full-url=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4.png\" data-link=\"https:\/\/www.g-portal.com\/wiki\/de\/untitled-reusable-block-2\/2de-1024x549-4\/\" class=\"wp-image-1763\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/2DE-1024x549-4-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Klicke auf &#8222;<strong>Meine Server<\/strong>&#8222;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2.png\" alt=\"\" data-id=\"1766\" data-full-url=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2.png\" data-link=\"https:\/\/www.g-portal.com\/wiki\/de\/untitled-reusable-block-2\/3de-1024x549-2\/\" class=\"wp-image-1766\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/3DE-1024x549-2-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">W\u00e4hle den gew\u00fcnschten Server aus<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2.png\" alt=\"\" data-id=\"1769\" data-full-url=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2.png\" data-link=\"https:\/\/www.g-portal.com\/wiki\/de\/untitled-reusable-block-2\/4de-1024x549-2\/\" class=\"wp-image-1769\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/4DE-1024x549-2-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Klicke links auf &#8222;<strong>Backup erstellen<\/strong>&#8222;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2.png\" alt=\"\" data-id=\"1772\" data-full-url=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2.png\" data-link=\"https:\/\/www.g-portal.com\/wiki\/de\/untitled-reusable-block-2\/5de-1024x549-2\/\" class=\"wp-image-1772\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/5DE-1024x549-2-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Klicke auf den Button &#8222;<strong>Backup erstellen<\/strong>&#8222;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2.png\" alt=\"\" data-id=\"1775\" data-full-url=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2.png\" data-link=\"https:\/\/www.g-portal.com\/wiki\/de\/untitled-reusable-block-2\/6de-1024x549-2\/\" class=\"wp-image-1775\" srcset=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2.png 1024w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2-300x161.png 300w, https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/6DE-1024x549-2-768x412.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Das erstellte Backup erscheint in der Liste<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Wie werde ich Admin?<\/h3>\n\n\n\n<ol><li>Logge dich in dein <strong>GPORTAL Konto<\/strong> ein <\/li><li>W\u00e4hle den gew\u00fcnschten Server aus<\/li><li>Klicke im linken Men\u00fc auf &#8222;<strong>Basiseinstellungen<\/strong>&#8222;<\/li><li>Stoppe den Server<\/li><li>Trage unter &#8222;<strong>Administrator Passwort<\/strong>&#8220; das gew\u00fcnschte Passwort ein<\/li><li><strong>Speicher<\/strong> die Einstellungen und starte den <strong>Server neu<\/strong><\/li><\/ol>\n\n\n\n<p>Dr\u00fccke im Spiel die Taste &#8222;<strong>\u00d6<\/strong>&#8220; und gebe folgenden Befehl ein:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\/GM DEINADMINPASSWORT<\/code><\/pre>\n\n\n\n<div class='hint hint--Danger'><p><strong>Achtung<\/strong>Tastaturbefehle funktionieren nur, wenn in der MySQL-Datenbank der Wert &#8222;isGM&#8220; auf &#8222;1&#8220; gesetzt ist.<br>Solltest du nicht sicher sein, wie du dies umstellst, wende dich bitte an unser Customer Happiness Team.<br><\/p><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Wie ist die Serverkonfiguration aufgebaut?<\/h3>\n\n\n\n<table>\n<tbody><tr>\n<th> Variable <\/th>\n<th> Information\n<\/th><\/tr>\n<tr>\n<td> &lt;ID&gt;XXXXXXXX%&lt;\/ID&gt; <\/td>\n<td> Diese ID wird vom Server zugewiesen und darf <b>nicht<\/b> vom Kunden bearbeitet werden.\n<\/td><\/tr>\n<tr>\n<td> &lt;name&gt;G-Portal.com LiF Serverhosting&lt;\/name&gt;<\/td>\n<td> In dieser Variable legt Ihr den Server Namen fest. Dieser darf nicht l\u00e4nger als 63 Zeichen sein.\n<\/td><\/tr>\n<tr>\n<td> &lt;password&gt;&lt;\/password&gt; <\/td>\n<td> Soll der Server ein Passwort haben, so k\u00f6nnt Ihr dieses hier einstellen. Kein Wert bedeutet &#8222;Kein Passwort&#8220;. Das Passwort darf nicht l\u00e4nger als 32 Zeichen sein.\n<\/td><\/tr>\n<tr>\n<td> &lt;adminPassword&gt;&lt;\/adminPassword&gt; <\/td>\n<td> Hier setzt Ihr das Admin-Passwort fest. Dies wird ben\u00f6tigt um den Server zu administrieren. Sollte der Wert leer sein, so wird der Admin-Modus deaktiviert. Auch hier darf das Passwort nicht l\u00e4nger als 32 Zeichen sein.\n<\/td><\/tr>\n<tr>\n<td> &lt;mode&gt;Sandbox&lt;\/mode&gt; <\/td>\n<td> Diese Variable dient als Platzhalter f\u00fcr die Zukunft und beinhaltet keine Aktion.\n<\/td><\/tr>\n<tr>\n<td> &lt;isActive&gt;1&lt;\/isActive&gt; <\/td>\n<td> Mit &#8222;isActive&#8220; stellt Ihr ein, ob der Server in der Liste zu finden Sein soll <b>(Wert: 1)<\/b> oder nicht <b>(Wert: 0)<\/b>.\n<\/td><\/tr>\n<tr>\n<td> &lt;skillsStatsMult&gt;10&lt;\/skillsStatsMult&gt; <\/td>\n<td> Skill Multiplikator, 1 ist Vanilla. Minimalwert ist 0.1, der Maximalwert ist 100.\n<\/td><\/tr>\n<tr>\n<td> &lt;skillcap&gt;600&lt;\/skillcap&gt; <\/td>\n<td> Menge der maximalen Skillpunkte, 600 ist Vanilla. Minimalwert ist 200, der Maximalwert ist 3000.\n<\/td><\/tr>\n<tr>\n<td> &lt;terraformingSpeed&gt;4&lt;\/terraformingSpeed&gt; <\/td>\n<td> Legt fest, wie schnell ein Tunnel erbaut werden kann. Der <b>Maximalwert<\/b> (60) sollte hierbei nicht \u00fcberschritten werden.\n<\/td><\/tr>\n<tr>\n<td> &lt;craftingPeriod&gt;60&lt;\/craftingPeriod&gt; <\/td>\n<td> Dieser Wert steht f\u00fcr die Ticks (vergleichbar mit Sekunden) die z.B. f\u00fcr das Brennen von Objekten ben\u00f6tigt werden. Dieser Wert sollte zwischen <b>1<\/b> und <b>3600<\/b> liegen.\n<\/td><\/tr>\n<tr>\n<td> &lt;animalBFPeriod&gt;60&lt;\/animalBFPeriod&gt; <\/td>\n<td> Dieser Wert steht f\u00fcr die Ticks (Vergleichbar mit Sekunden) die z.B. f\u00fcr das Z\u00fcchten von neuen Tieren oder das Wachsen von Getreide ben\u00f6tigt werden. Dieser Wert sollte zwischen <b>1<\/b> und <b>600<\/b> liegen.\n<\/td><\/tr>\n<tr>\n<td> &lt;dayCycle&gt;3&lt;\/dayCycle&gt; <\/td>\n<td> Dieser Wert legt fest, nach wie viele Echtzeitstunden ein Spieltag dauert. Der Standardwert betr\u00e4gt 3. Der Wert sollte zwischen <b>0.5<\/b> und <b>24<\/b> liegen. Zu beachten ist, das damit z.B. das Wachstum von B\u00e4umen beeinflusst wird.\n<\/td><\/tr>\n<tr>\n<td> &lt;animalsCount&gt;0&lt;\/animalsCount&gt; <\/td>\n<td> Mit diesem Wert setzt ihr das Maximum von zu spawnenden Tieren fest. Der Wert sollte zwischen <b>0<\/b> und <b>100<\/b> liegen, da es andernfalls zu Lags f\u00fchren kann.\n<\/td><\/tr>\n<tr>\n<td> &lt;maxPlayers&gt;24&lt;\/maxPlayers&gt; <\/td>\n<td> Der &#8222;maxPlayers&#8220; Wert gibt die Anzahl der maximalen Spieler anzahl des Servers an und darf <b>nicht<\/b> ge\u00e4ndert werden.\n<\/td><\/tr>\n<\/tbody><\/table>\n\n\n\n<h3 class=\"wp-block-heading\">Welche GM Befehle gibt es?<\/h3>\n\n\n\n<table>\n<tbody><tr>\n<th> Befehle <\/th>\n<th> Funktion\n<\/th><\/tr>\n<tr>\n<td> \/gm <\/td>\n<td> Mit diesem Befehle werden die Gamemaster Befehle in der Console gestartet.\n<\/td><\/tr>\n<tr>\n<td> \/gm password <\/td>\n<td> Damit authentifizierst du dich als Gamemaster im Spiel.\n<\/td><\/tr>\n<tr>\n<td> \/add &#8222;ITEM NAME&#8220; 1 100 20000 <\/td>\n<td> So kannst du dir ein Item im Spiel geben. Die Nummerierung lautet wie folgt, 1 = Menge, 100 = Qualit\u00e4t, 20000 = Haltbarkeit.\n<\/td><\/tr>\n<tr>\n<td> \/complete <\/td>\n<td> Der Befehl stellt das zu bauende Geb\u00e4ude direkt fertig. Damit das auch funktioniert, muss der Spieler einen direkten Blick auf das entsprechende Geb\u00e4ude haben.\n<\/td><\/tr>\n<tr>\n<td> \/setmyskill &#8222;Skillname&#8220; 100 <\/td>\n<td> So kannst du dir einen Skill auf die maximale Stufe stellen. Alternativ kann man auch die SkillID dazu nutzen.\n<\/td><\/tr>\n<tr>\n<td> \/reagents <\/td>\n<td> Dieser Befehl gibt dir alle m\u00f6glichen Reagenzien im Spiel f\u00fcr Alchemie.\n<\/td><\/tr>\n<tr>\n<td> \/alligment -1000\/1000 <\/td>\n<td> Somit kannst du die Ausrichtung des Charakters im Spiel \u00e4ndern. M\u00f6gliche Werte sind -1000 bis 1000.\n<\/td><\/tr>\n<tr>\n<td> \/setmystat ID MENGE <\/td>\n<td> So kannst du deine Stats im Spiel auf einen beliebigen Wert \u00e4ndern. Maximaler Wert ist 100. Die IDs lauten wie Folgt, 0 = St\u00e4rke, 1 = Beweglichkeit, 2 = Verfassung, 3 = Willenskfraft, 4 = Inteligenz.\n<\/td><\/tr>\n<tr>\n<td> \/weather ART <\/td>\n<td> Damit kannst du das Wetter \u00e4ndern, die Arten lauten wie folgt: Fair, Cloudy und Shower.\n<\/td><\/tr>\n<tr>\n<td> \/grow <\/td>\n<td> Damit kannst du den Wachstum deiner Felder beschleunigen. Du musst den Befehl 4 mal in folge nutzen, damit man eine \u00c4nderung sieht.\n<\/td><\/tr>\n<tr>\n<td> \/delobj <\/td>\n<td> So kannst du ein Geb\u00e4ude wieder l\u00f6schen. Du musst es daf\u00fcr direkt angucken.\n<\/td><\/tr>\n<tr>\n<td> \/addobj ID <\/td>\n<td> Damit kannst du ein Geb\u00e4ude in der Welt platzieren. Eine entsprechende Liste ist derzeit in Arbeit.\n<\/td><\/tr>\n<\/tbody><\/table>\n\n\n\n<h2 class=\"wp-block-heading\">Grundlegende Fragen \/ FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Wie verbinde ich via Steam zum Server?<\/h3>\n\n\n\n<ol><li>\u00d6ffne Steam und klicke auf &#8222;<strong>Anzeige<\/strong>&#8222;<\/li><li>Klicke auf &#8222;<strong>Server<\/strong>&#8222;<\/li><li>Navigiere zu &#8222;<strong>Favoriten<\/strong>&#8220; und dr\u00fccke im freien Feld die rechte Maustaste<\/li><li>Trage <strong>IP und Query Port<\/strong> deines Servers ein<\/li><li><strong>Aktualisiere<\/strong> die Favoriten<\/li><li><strong>Doppelklicke<\/strong> auf den neuen Eintrag, um zu verbinden<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Life is Feudal ist eine realistische Mittelalter Simulation, in der du alles ver\u00e4ndern kannst. <\/p>\n<p>Erlerne einen Beruf und verbessere deine F\u00e4higkeiten durch Aus\u00fcbung des Berufes.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Life is Feudal Server Einstellungen - GPORTAL Wiki<\/title>\n<meta name=\"description\" content=\"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach &amp; unkompliziert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Life is Feudal Server Einstellungen - GPORTAL Wiki\" \/>\n<meta property=\"og:description\" content=\"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach &amp; unkompliziert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/\" \/>\n<meta property=\"og:site_name\" content=\"GPORTAL Wiki\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T14:01:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T14:44:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\" \/>\n<meta name=\"author\" content=\"Aline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/\",\"name\":\"Life is Feudal Server Einstellungen - GPORTAL Wiki\",\"isPartOf\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\",\"datePublished\":\"2019-07-26T14:01:54+00:00\",\"dateModified\":\"2021-09-03T14:44:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/c001def8bbe3a6a9e5bdf0ed6ac55bf1\"},\"description\":\"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach & unkompliziert.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\",\"contentUrl\":\"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.g-portal.com\/wiki\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life is Feudal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#website\",\"url\":\"https:\/\/www.g-portal.com\/wiki\/en\/\",\"name\":\"GPORTAL Wiki\",\"description\":\"GPORTAL Wiki\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.g-portal.com\/wiki\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/c001def8bbe3a6a9e5bdf0ed6ac55bf1\",\"name\":\"Aline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8e0ba9417aba014a120f24b9615fd4b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8e0ba9417aba014a120f24b9615fd4b2?s=96&d=mm&r=g\",\"caption\":\"Aline\"},\"url\":\"https:\/\/www.g-portal.com\/wiki\/de\/author\/aline\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Life is Feudal Server Einstellungen - GPORTAL Wiki","description":"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach & unkompliziert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/","og_locale":"de_DE","og_type":"article","og_title":"Life is Feudal Server Einstellungen - GPORTAL Wiki","og_description":"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach & unkompliziert.","og_url":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/","og_site_name":"GPORTAL Wiki","article_published_time":"2019-07-26T14:01:54+00:00","article_modified_time":"2021-09-03T14:44:16+00:00","og_image":[{"url":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png"}],"author":"Aline","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Aline","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/","url":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/","name":"Life is Feudal Server Einstellungen - GPORTAL Wiki","isPartOf":{"@id":"https:\/\/www.g-portal.com\/wiki\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage"},"image":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png","datePublished":"2019-07-26T14:01:54+00:00","dateModified":"2021-09-03T14:44:16+00:00","author":{"@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/c001def8bbe3a6a9e5bdf0ed6ac55bf1"},"description":"In unserem Wiki erf\u00e4hrst du, wie du deinen LiF:Your Own Server konfiguieren und bearbeiten kannst. Schnell, einfach & unkompliziert.","breadcrumb":{"@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#primaryimage","url":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png","contentUrl":"https:\/\/www.g-portal.com\/wiki\/wp-content\/uploads\/2020\/01\/1DE-1024x549-3.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.g-portal.com\/wiki\/de\/life-is-feudal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.g-portal.com\/wiki\/en\/"},{"@type":"ListItem","position":2,"name":"Life is Feudal"}]},{"@type":"WebSite","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#website","url":"https:\/\/www.g-portal.com\/wiki\/en\/","name":"GPORTAL Wiki","description":"GPORTAL Wiki","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.g-portal.com\/wiki\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/c001def8bbe3a6a9e5bdf0ed6ac55bf1","name":"Aline","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.g-portal.com\/wiki\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8e0ba9417aba014a120f24b9615fd4b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e0ba9417aba014a120f24b9615fd4b2?s=96&d=mm&r=g","caption":"Aline"},"url":"https:\/\/www.g-portal.com\/wiki\/de\/author\/aline\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/697"}],"collection":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/comments?post=697"}],"version-history":[{"count":15,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/697\/revisions"}],"predecessor-version":[{"id":8581,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/posts\/697\/revisions\/8581"}],"wp:attachment":[{"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/media?parent=697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/categories?post=697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.g-portal.com\/wiki\/de\/wp-json\/wp\/v2\/tags?post=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}